{"id":149988,"date":"2016-04-12T14:39:45","date_gmt":"2016-04-12T13:39:45","guid":{"rendered":"http:\/\/www.union.fr\/?p=149988"},"modified":"2016-04-12T16:19:07","modified_gmt":"2016-04-12T15:19:07","slug":"du-viagra-en-echange-dun-vote","status":"publish","type":"post","link":"https:\/\/www.union.fr\/actus\/insolite\/du-viagra-en-echange-dun-vote-149988.html","title":{"rendered":"Du viagra en \u00e9change de bulletins de vote"},"content":{"rendered":"<p>Si la ville de Suwon \u00e9tait d\u00e9j\u00e0 r\u00e9put\u00e9e \u00e0 l&rsquo;\u00e9chelle internationale pour sa sp\u00e9cialit\u00e9 \u00e0 base de viande de b\u0153uf grill\u00e9e et son stade de football, sa notori\u00e9t\u00e9 vient de marquer un point suppl\u00e9mentaire avec une actualit\u00e9 plut\u00f4t originale !<br \/> Le parquet de cette ville sud-cor\u00e9enne situ\u00e9e \u00e0 30km de S\u00e9oul a ouvert mardi une enqu\u00eate pour achat de votes. Un candidat (dont le nom n&rsquo;est pas encore d\u00e9voil\u00e9) est soup\u00e7onn\u00e9 d&rsquo;avoir orient\u00e9 le bulletin des \u00e9lecteurs en sa faveur en \u00e9change de viagra.<\/p> <p>\u00ab\u00a0<em>Nous devons encore v\u00e9rifier ces accusations. Si elles \u00e9taient confirm\u00e9es, il s&rsquo;agirait d&rsquo;une violation du code \u00e9lectoral<\/em>\u00ab\u00a0, a d\u00e9clar\u00e9 un porte-parole du parquet de Suwon \u00e0 l&rsquo;AFP.<\/p> <p><strong>A lire aussi &gt;&gt;<\/strong> <a href=\"http:\/\/www.union.fr\/sexo\/sexualite-et-sante\/viagra-recreatif-la-derive-461.html#post-461\">Viagra r\u00e9cr\u00e9atif, la d\u00e9rive<\/a><\/p> <h2>Des pots-de-vin qui peuvent co\u00fbter jusqu&rsquo;\u00e0 5 ans de prison<\/h2> <p>Si les faits sont av\u00e9r\u00e9s, le candidat encourt jusqu&rsquo;\u00e0 5 ans de prison et 10 millions de Won (7 600\u20ac environ). L&rsquo;\u00e9lecteur corrompu peut quant \u00e0 lui recevoir une amende allant jusqu&rsquo;\u00e0 50 fois le montant du pot-au-vin re\u00e7u.<br \/> L\u2019enqu\u00eate devra aussi d\u00e9terminer la fa\u00e7on dont ce candidat a obtenu un grand nombre de ces traitements, strictement prescrits sous ordonnance m\u00e9dicale.<\/p> <p>Confondre \u00e9rection et \u00e9lection, quand m\u00eame !<\/p> <p>(<em>Image \u00e0 la une : Getty images<\/em>)<\/p> ","protected":false},"excerpt":{"rendered":"<p>Quand les pilules bleues se retrouvent au c\u0153ur d&rsquo;une enqu\u00eate en Cor\u00e9e du Sud&#8230;<\/p>\n","protected":false},"author":4,"featured_media":149989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,20],"tags":[720,655,136],"class_list":["post-149988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-insolite","tag-coree-du-sud","tag-legislation","tag-viagra"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/149988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=149988"}],"version-history":[{"count":3,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/149988\/revisions"}],"predecessor-version":[{"id":150000,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/149988\/revisions\/150000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/149989"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=149988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=149988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=149988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}