{"id":153561,"date":"2024-09-19T18:00:17","date_gmt":"2024-09-19T16:00:17","guid":{"rendered":"http:\/\/www.union.fr\/?p=153561"},"modified":"2024-09-17T16:04:15","modified_gmt":"2024-09-17T14:04:15","slug":"30-ans-mon-anniversaire-ma-fete","status":"publish","type":"post","link":"https:\/\/www.union.fr\/recits\/30-ans-mon-anniversaire-ma-fete-153561.html","title":{"rendered":"Mon anniversaire, ma f\u00eate"},"content":{"rendered":"<p>Bonjour \u00e0 tous les lecteurs et lectrices d&rsquo;Union, j&rsquo;ai une <a href=\"https:\/\/www.union.fr\/recits\">histoire de sexe<\/a> \u00e0 vous raconter ! Je vous \u00e9cris aujourd&rsquo;hui pour vous raconter <strong>le cadeau<\/strong> que m&rsquo;a fait mon mari pour mon trenti\u00e8me anniversaire. Car, voyez-vous, mon mari est un homme formidable et il lui trottait dans l&rsquo;id\u00e9e depuis quelque temps de <strong>me partager avec un homme seul<\/strong>. C&rsquo;est donc tout naturellement qu&rsquo;il m&rsquo;a propos\u00e9 de m&rsquo;offrir un homme !<\/p>  <p><a href=\"https:\/\/boutique.union.fr\/\"><div class=\"wrap-img\" id=\"wrap-img-357959\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"wp-image-357959 size-medium aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/06\/prestige-16-widget-3-1-300x250.png\" alt=\"boutique union\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <h2>Un Ost\u00e9opathe dou\u00e9 de ses mains et de sa bouche<\/h2> <p>Libertins depuis une petite ann\u00e9e, <strong>l&rsquo;\u00e9change sexuel<\/strong> n&rsquo;\u00e9tait pas une nouveaut\u00e9 pour nous, cependant je dois vous avouer que je suis tomb\u00e9e de ma chaise. Qu&rsquo;un homme ose, de lui-m\u00eame, laisser sa femme faire l&rsquo;amour avec un autre homme, c&rsquo;\u00e9tait absolument incroyable. L&rsquo;id\u00e9e me plaisait, c&rsquo;\u00e9tait ind\u00e9niable, j&rsquo;ai donc accept\u00e9 de tenter l&rsquo;exp\u00e9rience. Il s&rsquo;est occup\u00e9 seul de la recherche et de la prise de contact <strong>avec le cadeau en question<\/strong>, je n&rsquo;ai rien su, ni rien voulu savoir. Le jour J, je n&rsquo;ai eu qu&rsquo;un pr\u00e9nom, une adresse dans Paris, et un num\u00e9ro de t\u00e9l\u00e9phone au cas o\u00f9. C&rsquo;\u00e9tait assez inqui\u00e9tant de ne pas savoir avec qui j&rsquo;allais passer la soir\u00e9e, mais en m\u00eame temps cela m&rsquo;a forc\u00e9e \u00e0 avoir une confiance aveugle en mon mari, cela m&rsquo;a pr\u00e9par\u00e9e \u00e0 m&rsquo;abandonner.<\/p> <p>Par\u00e9e de mes plus beaux atours et d\u00e9licatement parfum\u00e9e, j&rsquo;ai donc sonn\u00e9 \u00e0 un immeuble inconnu, pris un ascenseur, et rencontr\u00e9 mon cadeau, qui m&rsquo;a souhait\u00e9 en riant un tr\u00e8s joyeux anniversaire. Un verre de champagne ros\u00e9 plus tard, ce magnifique ost\u00e9opathe m&rsquo;a propos\u00e9 un <a href=\"https:\/\/www.union.fr\/recits\/massage-tres-coquin-188593.html\">massage<\/a>. Quelle bonne id\u00e9e. J&rsquo;ai donc fait tomber ma robe l\u00e9g\u00e8re et mon soutien-gorge, ne gardant qu&rsquo;une <strong>culotte en dentelle et mes hauts talons<\/strong>. Je me suis allong\u00e9e \u00e0 plat ventre sur la table de massage, devant mon beau cadeau. Il s&rsquo;est av\u00e9r\u00e9 que mon masseur n&rsquo;\u00e9tait pas seulement beau, mais aussi extr\u00eamement dou\u00e9 de ses mains. Ce massage fut un v\u00e9ritable d\u00e9lice des sens. Ses doigts experts ont gliss\u00e9 en harmonie de mes \u00e9paules \u00e0 mon dos, de mes bras \u00e0 mes cuisses, jusqu&rsquo;\u00e0 mon entrejambe qui a aussi profit\u00e9 d&rsquo;un massage des plus agr\u00e9ables&#8230;<\/p> <p>Encourag\u00e9 par mes soupirs, mon bel inconnu m&rsquo;a retourn\u00e9e sur le dos, a \u00f4t\u00e9 ma culotte et s&rsquo;est appliqu\u00e9 \u00e0 me prouver qu&rsquo;il n&rsquo;\u00e9tait pas dou\u00e9 qu&rsquo;avec ses doigts. Il m&rsquo;a ainsi <strong>l\u00e9ch\u00e9e et suc\u00e9e<\/strong> pendant un temps infini. Je g\u00e9missais. Mon corps n&rsquo;en pouvait plus de tant de plaisir, je tremblais de tous mes membres et je ne d\u00e9sirais plus qu&rsquo;une chose, <strong>prendre son sexe entre mes l\u00e8vres<\/strong> ! J&rsquo;ai donc exprim\u00e9 mon besoin et il a \u00e9t\u00e9 trop heureux d&rsquo;accepter. Je me suis assise et il a pris ma bouche d&rsquo;une mani\u00e8re aussi sauvage que sensuelle. J&rsquo;ai retir\u00e9 ses v\u00eatements et me suis coll\u00e9e contre son corps br\u00fblant, ondulant mes hanches contre son sexe tendu. Nos l\u00e8vres semblaient ne plus vouloir se quitter, mais son sexe m&rsquo;attirait trop, et j&rsquo;ai doucement fait glisser ma langue et mes l\u00e8vres contre son torse, puis de plus en plus bas !<\/p> <p>Je me suis longuement attard\u00e9e autour de la base de son sexe, explorant chaque centim\u00e8tre afin de conna\u00eetre ses points les plus sensibles. Les ayant d\u00e9couverts, je me suis appliqu\u00e9e \u00e0 les l\u00e9cher avec d\u00e9lectation, heureuse d&rsquo;entendre ses soupirs de plaisir. Enfin ma langue est mont\u00e9e sur <strong>sa magnifique \u00e9rection<\/strong> et je l&rsquo;ai pris \u00e0 pleine bouche, faisant jouer ma langue contre son gland\u00a0en montant et descendant mes l\u00e8vres le long de sa verge tout en lui lan\u00e7ant ces regards torrides qui, je le sais, excitent tant mon mari. Tr\u00e8s attir\u00e9 par mes fesses tendues vers le ciel, mon cadeau m&rsquo;a r\u00e9clam\u00e9 un <a href=\"https:\/\/www.union.fr\/recits\/la-69e-case-13669.html\">69 <\/a>que je lui ai imm\u00e9diatement offert. Il a recommenc\u00e9 \u00e0 l\u00e9cher mon clitoris gonfl\u00e9 \u00e0 bloc tout en mettant un doigt dans mon vagin.<\/p> <p><a href=\"https:\/\/video.union.fr\/masseur-mon-frere\"><div class=\"wrap-img\" id=\"wrap-img-440051\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-440051 size-full aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2024\/09\/widget_vod_masseurmonfrere.gif\" alt=\"\" width=\"300\" height=\"300\" \/><\/div><\/a><\/p> <h2>P\u00e9n\u00e9tration et sodomie avec mon amant<\/h2> <p>Une inspiration soudaine lui a fait faire des cercles rapides et intenses avec l&rsquo;extr\u00e9mit\u00e9 de son doigt, ce qui m&rsquo;a fait <strong>hurler de plaisir<\/strong> ! Il y avait presque de la violence dans l&rsquo;intensit\u00e9 de son mouvement, et cela m&rsquo;a donn\u00e9 encore plus de sensations. J&rsquo;avais maintenant envie de remplacer ses doigts par sa virilit\u00e9 dans ma chatoune ! D\u00e8s que je lui ai fait part de <strong>mon besoin intense de sa queue<\/strong>, il a \u00e9t\u00e9 chercher un pr\u00e9servatif qu&rsquo;il a enfil\u00e9 avec dext\u00e9rit\u00e9 d&rsquo;une main sans m\u00eame arr\u00eater de me donner du plaisir avec son autre main et sa langue. Il s&rsquo;est introduit en moi, doucement, puis plus intens\u00e9ment, jusqu&rsquo;\u00e0 me secouer comme un prunier ! Les positions se sont encha\u00een\u00e9es, me faisant prendre de plus en plus de plaisir, me faisant crier de plus en plus fort.<\/p> <p>Au bout d&rsquo;un long moment de plaisir sexuel partag\u00e9, il a caress\u00e9 <strong>l&rsquo;entr\u00e9e de mon anus<\/strong> et m&rsquo;a propos\u00e9 une <a href=\"https:\/\/www.union.fr\/recits\/sodomie-recits\/sodomie-vengeance-de-blonde-316448.html\">sodomie <\/a>que j&rsquo;ai accept\u00e9e avec quelques craintes&#8230; Son membre \u00e9tait tr\u00e8s imposant. Il\u00a0m&rsquo;a introduit un doigt, puis plusieurs et a commenc\u00e9 un long et tr\u00e8s agr\u00e9able travail de pr\u00e9paration. Avec douceur, d&rsquo;abord, il a introduit son sexe dans mon orifice dilat\u00e9. Il est\u00a0all\u00e9 de plus en plus profond\u00e9ment jusqu&rsquo;\u00e0 <strong>remplir tout mon petit trou de son sexe<\/strong>, jusqu&rsquo;\u00e0 la garde. Pris dans notre plaisir, il s&rsquo;est mis \u00e0 <strong>me pilonner avec fougue<\/strong>, jusqu&rsquo;\u00e0 ce que je demande gr\u00e2ce, \u00e9puis\u00e9e par une partie de sexe si longue et si\u00a0intense. Comme dernier cadeau, je lui ai demand\u00e9 de r\u00e9pandre sa semence sur mes seins, ce qui m&rsquo;a permis de le sucer une derni\u00e8re fois.<\/p> <p>Je suis rentr\u00e9e ainsi pour retrouver mon mari, tout \u00e9moustill\u00e9 par les nombreuses photos de nos \u00e9bats qu&rsquo;il avait d\u00e9j\u00e0 re\u00e7ues sur notre ordinateur. Il \u00e9tait tout aussi excit\u00e9 de me retrouver, si bien que nous avons fait l&rsquo;amour avant de nous endormir, puis une autre fois pendant la nuit. Nous \u00e9tions si inspir\u00e9s par cette exp\u00e9rience hors du commun ! Je ressors <strong>d\u00e9sinhib\u00e9e<\/strong> de cette aventure. Je tends de plus en plus vers <strong>cette femme lib\u00e9r\u00e9e<\/strong> que j&rsquo;ai toujours voulu devenir. Mon mari, quant \u00e0 lui, a ador\u00e9 que je le <strong>cocufie<\/strong>, ce qui veut dire, vous vous en doutez bien, que cette grande premi\u00e8re n&rsquo;est s\u00fbrement pas la derni\u00e8re et qu&rsquo;elle en appelle d\u00e9j\u00e0 d&rsquo;autres !<\/p> <h3>A lire aussi<\/h3> <p><a href=\"https:\/\/www.union.fr\/recits\/le-sandwich-viril-153060.html\">Avec mon ami devant mon mari<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/recits\/plaisir-doffrir-330473.html\">Plaisir d&rsquo;offrir !<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/recits\/bon-anniversaire%e2%80%89-152698.html\">Bon anniversaire !<\/a><\/p>  ","protected":false},"excerpt":{"rendered":"<p>\u00c9lodie, 30 ans, re\u00e7oit un cadeau de la part de son mari pour son anniversaire : il lui offre un homme, rien que pour elle.<\/p>\n","protected":false},"author":7,"featured_media":153565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5944,5937,5955,5938,5949,5936,5,8],"tags":[538,354,613,1116,112,336,154,109,569,509,643,2177,115],"class_list":["post-153561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libertinage-recits","category-cunnilingus-recits","category-histoire-de-sexe-fantasme-recits","category-fellation-recits","category-infidelite-adultere-recits","category-sodomie-recits","category-menu_site","category-recits","tag-538","tag-analsodomie","tag-anniversaire","tag-cadeau","tag-cunnilingus","tag-ejaculation","tag-erection","tag-fellation","tag-libertin","tag-libertinage","tag-massage","tag-penetration-vaginale","tag-sodomie"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/153561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=153561"}],"version-history":[{"count":9,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/153561\/revisions"}],"predecessor-version":[{"id":440309,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/153561\/revisions\/440309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/153565"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=153561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=153561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=153561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}