{"id":156990,"date":"2024-03-19T12:00:10","date_gmt":"2024-03-19T10:00:10","guid":{"rendered":"http:\/\/www.union.fr\/?p=156990"},"modified":"2024-03-13T17:36:32","modified_gmt":"2024-03-13T15:36:32","slug":"jai-pas-fait-mes-devoirs%e2%80%89","status":"publish","type":"post","link":"https:\/\/www.union.fr\/recits\/jai-pas-fait-mes-devoirs%e2%80%89-156990.html","title":{"rendered":"J\u2019ai pas fait mes devoirs\u2009!"},"content":{"rendered":"<p>Encore une fois, je n\u2019ai pas fait mes devoirs\u2009! \u00c7a avait le don de rendre mon ch\u00e9ri, Jules, compl\u00e8tement fou. On joue souvent \u00e0 des jeux de r\u00f4les un peu r\u00e9gressifs\u00a0: l\u2019\u00e9tudiante et le professeur, la secr\u00e9taire et le patron, la pom-pom girl et le joueur de football (oui, celui-l\u00e0 est particulier, je vous l\u2019accorde\u2009!)\u2026 et l\u00e0, je n\u2019avais pas fait mes devoirs\u2009! J\u2019avais pris soin, avant de le d\u00e9ranger dans sa partie de jeux vid\u00e9o, d\u2019avoir enfil\u00e9 une petite jupe tr\u00e8s courte, un petit haut vert fluo et de m\u2019\u00eatre fait deux couettes bien hautes. Voici mon <a href=\"https:\/\/www.union.fr\/recits\">histoire de sexe<\/a>.<\/p> <h2>Une imagination toute mouill\u00e9e<\/h2> <p>Quand il m\u2019a vu arriver dans cet accoutrement avec ma petite moue boudeuse,<strong> mon homme m\u2019a imm\u00e9diatement prise \u00e0 la renverse sur ses genoux,<\/strong> abandonnant d\u2019une traite sa partie virtuelle en cours. Il a relev\u00e9 ma jupe au-dessus de mes deux petites miches et m\u2019a donn\u00e9 une petite tape sur le fessier. \u00ab\u202f<em>Oh, tu as mis ta petite culotte blanche en coton, en plus\u2009!<\/em>\u202f\u00bb s\u2019est-il \u00e9merveill\u00e9. \u00ab\u202f<em>Mais je vais quand m\u00eame te la retirer, elle me g\u00eane terriblement dans mes mouvements.<\/em>\u202f\u00bb <strong>Tr\u00e8s doucement, il a fait coulisser ma culotte entre mes cuisses.<\/strong><\/p> <p><a href=\"https:\/\/video.union.fr\/sublime-milena\"><div class=\"wrap-img\" id=\"wrap-img-434685\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"aligncenter wp-image-434685 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2024\/03\/widget_vod_sublime_melina-300x250.jpg\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p>Il a certainement d\u00fb s\u2019apercevoir qu\u2019elle \u00e9tait tremp\u00e9e, mais il n\u2019a rien dit. \u00ab\u202f<em>Bon alors, tu n\u2019as pas fait tes devoirs, c\u2019est \u00e7a\u2009? Mmh, laisse-moi r\u00e9fl\u00e9chir \u00e0 une punition\u2026\u202f<\/em>\u00bb Jules avait toujours <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-on-a-beaucoup-dimagination-union-13595.html#post-13595\">beaucoup d\u2019imagination<\/a>, j\u2019\u00e9tais impatiente qu\u2019il en trouve une nouvelle\u2009! Tout en r\u00e9fl\u00e9chissant, i<strong>l faisait rougir mes deux petites fesses d\u2019une poigne tr\u00e8s ma\u00eetris\u00e9e.<\/strong><\/p> <h2>Fais ce que je te dis !<\/h2> <p>\u00c7a ne faisait pas mal du tout d\u2019ailleurs, c\u2019\u00e9tait assez agr\u00e9able. Il savait comment frapper, toujours sur la partie la plus charnue, en alternant une tape ferme et une caresse plus douce. \u00ab\u202f<em>Je sais\u2009!\u202f<\/em>\u00bb s\u2019est-il \u00e9cri\u00e9 comme un gosse.<strong> \u00ab\u202f<em>Tu vas devoir te tenir \u00e0 genoux, main sur la t\u00eate, langue pendante, et moi je vais t\u2019enfoncer ma bite jusqu\u2019au fond de la gorge.\u202f<\/em>\u00bb<\/strong> L\u2019id\u00e9e m\u2019excitait bien (surtout dite de cette fa\u00e7on-l\u00e0), m\u00eame si ce n\u2019\u00e9tait pas si original que \u00e7a. Je me suis donc mise dans un coin de la pi\u00e8ce, Jules a fait passer sa queue \u00e0 travers <a href=\"https:\/\/www.union.fr\/recits\/dun-coup-de-braguette-magique-287622.html#post-287622\">la braguette de son jean<\/a>. Il avait encore une demi-molle, mais une fois dans ma bouche, <strong>il s\u2019est mis \u00e0 bander bien dur instantan\u00e9ment.<\/strong><\/p> <p><a href=\"https:\/\/video.union.fr\/blondes\/une-blonde-deux-bi\"><div class=\"wrap-img\" id=\"wrap-img-434683\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-434683 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2024\/03\/widget_vod_blonde_bi-300x250.jpg\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p><strong>Un peu comme un cachet d\u2019aspirine au contact de l\u2019eau.<\/strong> \u00ab\u202f<em>Tire plus ta langue Lydie\u2009! Je veux te voir baver sur ton menton\u2009!\u202f<\/em>\u00bb Je la tirais le plus possible mais il \u00e9tait <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-cette-sauvage-a-eu-un-plaisir-violent-union-434320.html#post-434320\">vraiment impitoyable<\/a>. Il me tenait par les cheveux, et enfon\u00e7ait comme il pouvait mon visage sur son membre viril. \u00c7a m\u2019\u00e9touffait, et, me voyant suffoquer comme une malade, il a d\u00e9cid\u00e9 d\u2019arr\u00eater. \u00ab\u202f<em>Bon allez, c\u2019est bon\u2009! Le jeu est termin\u00e9, viens que je te baise\u2026\u202f<\/em>\u00bb Il s\u2019est allong\u00e9 lentement sur notre lit et je suis venue m\u2019empaler sur lui<em>. \u00ab\u202f\u00c0 toi de bosser\u2009!\u202f<\/em>\u00bb <strong>m\u2019a-t-il ordonn\u00e9.<\/strong><\/p> <h2>La d\u00e9livrance<\/h2> <p>J\u2019ai soulev\u00e9 puis redescendu mon bassin, avec une rapidit\u00e9 qui m\u2019\u00e9tonnait moi-m\u00eame, dans un mouvement qui se voulait le plus ample possible. \u00ab\u202f<em>Mmmh. Ooh. Encore\u2026\u202f<\/em>\u00bb Jules avait l\u2019air combl\u00e9. Il a tendu ses bras en haut comme s\u2019il s\u2019\u00e9tirait apr\u00e8s <a href=\"https:\/\/www.union.fr\/recits\/la-nuit-est-chaude-331245.html#post-331245\">une nuit agit\u00e9<\/a>. Il \u00e9tait compl\u00e8tement abandonn\u00e9 \u00e0 mes \u00e0-coups impulsifs.<strong> Plus je lui en donnais, plus cela coulissait facilement.<\/strong> Au bout d\u2019un moment il a l\u00e2ch\u00e9 un grand soupir saccad\u00e9, <strong>signe \u00e9vident d\u2019une \u00e9jaculation r\u00e9ussie.<\/strong> Il m\u2019a alors serr\u00e9e contre son torse et m\u2019a retir\u00e9 les \u00e9lastiques qui nouaient mes cheveux en couette.<\/p> <p><a href=\"https:\/\/video.union.fr\/gros-seins\/big-is-beautiful\"><div class=\"wrap-img\" id=\"wrap-img-434682\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-434682 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2024\/03\/widget_vod_big_is_beautiful-300x250.jpg\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p>\u00ab\u202f<em>Je te pr\u00e9f\u00e8re au naturel\u2026<\/em>\u202f\u00bb m\u2019a-t-il susurr\u00e9 \u00e0 l\u2019oreille tandis que nous \u00e9tions coll\u00e9s l\u2019un \u00e0 l\u2019autre, en position de c\u00e2lin. \u00ab\u202f<em>En tout cas merci, c\u2019\u00e9tait vraiment tr\u00e8s bon\u2009!<\/em>\u202f\u00bb<br \/> Pour un professeur, il savait \u00eatre s\u00e9v\u00e8re\u2026 mais juste\u2009!<\/p> <p><em>(Image \u00e0 la une : Getty Images)<\/em><\/p> <p><strong>A lire aussi &gt;&gt;\u00a0<\/strong><a href=\"http:\/\/www.union.fr\/recits\/week-end-coquin-avec-megane-13543.html\">Week-end coquin avec M\u00e9gane<\/a><br \/> \u00ab\u00a0<em>Nous nous sommes goinfr\u00e9 de biscuits au chocolat et nous avons fait passer tout \u00e7a avec des bi\u00e8res que mon amoureux avait planqu\u00e9es dans son sac. Il faisait\u00a0tellement moche dehors que nous n\u2019avions pas tr\u00e8s envie d\u2019aller d\u00e9couvrir les environs. Nous avons ouvert notre magazine pr\u00e9f\u00e9r\u00e9, et j\u2019ai lu \u00e0 voix haute.<\/em>\u00a0\u00bb <strong>M\u00e9gane.<\/strong><\/p> <p><strong>A lire aussi &gt;&gt;\u00a0<\/strong><a href=\"http:\/\/www.union.fr\/recits\/va-y-sport-154893.html\">Le prof de sport et l&rsquo;\u00e9tudiante coquine<\/a><br \/> \u00ab\u00a0<em>En une pouss\u00e9e seulement j\u2019en avais rentr\u00e9 la moiti\u00e9. Mathilde faisait moins la fi\u00e8re tout \u00e0 coup, je l\u2019entendais juste r\u00e2ler faiblement. J\u2019ai donn\u00e9 un deuxi\u00e8me coup de reins et je suis entr\u00e9 en entier. La garce \u00e9tait embroch\u00e9e comme un poulet et beaucoup moins bavarde.<\/em>\u00a0\u00bb <strong>St\u00e9phane.<\/strong><\/p>  ","protected":false},"excerpt":{"rendered":"<p>Lydie, 25 ans, Dunkerque, adore recevoir des punitions de son compagnon lors de leurs \u00e9bats sexuels.<\/p>\n","protected":false},"author":7,"featured_media":156992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[1556,109,1555,1557],"class_list":["post-156990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-menu_site","category-recits","tag-en-couple","tag-fellation","tag-jeux-de-roles","tag-jeux-sm"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/156990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=156990"}],"version-history":[{"count":5,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/156990\/revisions"}],"predecessor-version":[{"id":434954,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/156990\/revisions\/434954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/156992"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=156990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=156990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=156990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}