{"id":279810,"date":"2024-11-11T16:00:38","date_gmt":"2024-11-11T14:00:38","guid":{"rendered":"http:\/\/www.union.fr\/?p=279810"},"modified":"2024-11-05T17:33:11","modified_gmt":"2024-11-05T15:33:11","slug":"panthere-de-ville","status":"publish","type":"post","link":"https:\/\/www.union.fr\/recits\/panthere-de-ville-279810.html","title":{"rendered":"Panth\u00e8re de ville"},"content":{"rendered":"<p>Je m\u2019appelle Rick et je suis actuellement stagiaire dans une banque, travaillant toute la journ\u00e9e dans une grande tour \u00e0 la D\u00e9fense. <strong>C\u2019est mon premier job et ma premi\u00e8re exp\u00e9rience de ma vie \u00ab d\u2019adulte \u00bb<\/strong>. J\u2019ai quitt\u00e9 le cocon familial depuis quelques mois et j\u2019exp\u00e9rimente avec \u00e9tonnement la tranquille rengaine du m\u00e9tro-boulot-dodo. Pour sortir de ma routine, je voudrais partager avec vous mon <a href=\"https:\/\/www.union.fr\/recits\">histoire de sexe amateur<\/a>.<\/p> <h2>Rencontre sur le chemin du travail<\/h2> <p>Je prends un bus tous les matins pour me rendre au travail \u2013\u00a0s\u2019ensuit un nombre d\u2019appels, de rendez-vous et de reporting \u2013\u00a0puis je retourne chez moi me coucher. Parfois je vois un ou deux amis, parfois je mate un film. Comme c\u2019est nouveau, je retrouve toujours la sensation grisante de l\u2019inconnu, mais je comprends que les trentenaires puissent s\u2019\u00e9puiser \u00e0 force de conna\u00eetre la m\u00eame rengaine chaque jour.<\/p> <p>Dans mon bus quotidien, il y a toujours <strong>cette femme, que je regarde avec int\u00e9r\u00eat.<\/strong> Elle s\u2019habille en l\u00e9opard et porte des talons tr\u00e8s rouges. C\u2019est amusant de la voir plant\u00e9e l\u00e0, au milieu de toutes ces personnes qui sont tout de noir v\u00eatu, le teint gris, l\u2019air triste. On ne voit qu\u2019elle, et elle, semble ignorer le monde qui l\u2019entoure. J\u2019ai plusieurs fois essay\u00e9 d\u2019inventer sa vie. En me disant qu\u2019elle pouvait \u00eatre peut-\u00eatre <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-actrice-a-tout-prix-13542.html#post-13542\">actrice<\/a>, mannequin ou h\u00f4tesse pour une marque de luxe. Bien qu\u2019elle me paraisse plus \u00e2g\u00e9e que moi (sans doute une petite quarantaine) \u2013<strong>\u00a0je m\u2019imaginais qu\u2019elle avait une vie totalement folle, aux antipodes de ma douce routine<\/strong> qui s\u2019annon\u00e7ait \u00eatre mon lot quotidien durant les vingt prochaines ann\u00e9es.<\/p> <p><a href=\"https:\/\/livecam.union.fr\/fr\/\"><div class=\"wrap-img\" id=\"wrap-img-367688\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"size-medium wp-image-367688 aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/09\/3-2-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <h2>La pr\u00e9datrice chasse sa proie<\/h2> <p>Un soir, durant mon dernier mois de <a href=\"https:\/\/www.union.fr\/recits\/recits-illustres\/stage-intensif-146230.html#post-146230#item=1\">stage<\/a>, elle m\u2019a suivi jusqu&rsquo;\u00e0 chez moi\u2009! Au d\u00e9part, j\u2019ai cru que c\u2019\u00e9tait simplement une co\u00efncidence mais quand j\u2019ai commenc\u00e9 \u00e0 m\u2019engouffrer dans les petites ruelles, j\u2019ai su qu\u2019il n\u2019y avait plus de doute possible. Pour \u00eatre honn\u00eate, <strong>j\u2019ai eu un peu peur au d\u00e9but,<\/strong> \u00e7a vous flanque une de ses trouilles d\u2019\u00eatre suivi, quand bien m\u00eame il s\u2019agit d\u2019une <strong>adorable panth\u00e8re<\/strong>. Quand je lui ai dit \u00ab<em>\u2009Je peux vous aider\u2009?<\/em>\u2009\u00bb elle m\u2019a r\u00e9pondu qu\u2019elle avait remarqu\u00e9 que je la matais tous les jours dans le bus.<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>Elle m\u2019a dit qu\u2019elle avait demand\u00e9 \u00e0 son mari la permission de suivre ce jeune si myst\u00e9rieux qui la d\u00e9visageait tous les matins. \u00ab\u2009<em>Et me voil\u00e0\u2009!<\/em>\u2009\u00bb, a-t-elle dit, en me regardant avec app\u00e9tit. \u00c0 ce moment-l\u00e0, j\u2019ai soudain tout compris\u00a0:<strong> c\u2019\u00e9tait elle le pr\u00e9dateur et j\u2019\u00e9tais sa proie.<\/strong> Quel dr\u00f4le de retournement de situation\u2009! Je l\u2019ai laiss\u00e9e entrer chez moi et elle m\u2019a tout de suite pouss\u00e9 sur le lit. <strong>L\u00e0 elle m\u2019a suc\u00e9, c\u2019\u00e9tait la pipe du si\u00e8cle\u2009!<\/strong><\/p> <p>Elle a plant\u00e9 ses crocs dans la chair de ma cuisse, mes couilles tremblaient entre ses griffes et elle me pompait violemment, comme si sa vie en d\u00e9pendait. Quand elle voyait que j\u2019allais venir trop vite, elle s\u2019arr\u00eatait alors et pressait ses petits seins l\u2019un contre l\u2019autre ou <strong>me montrait sa belle chatte luisante<\/strong>\u2026 elle avait un corps de dingue pour son \u00e2ge. Une fois que je m\u2019\u00e9tais calm\u00e9, elle reprenait alors la fellation, un peu plus doucement et d\u00e9licatement. Une fois que j\u2019ai joui, elle s\u2019est l\u00e9ch\u00e9e les babines (ou c\u2019\u00e9tait tout comme) et m\u2019a laiss\u00e9 l\u00e0, en plan.<\/p> <p><em>\u00ab<strong>\u2009Je viendrais te retrouver, si j\u2019ai besoin&#8230;\u2009<\/strong><\/em>\u00bb, m\u2019a-t-elle juste dit, en claquant la porte. Ou alors \u00e9tait-ce le fouet qui venait de claquer\u2009? Et qu\u2019elle avait pris mon petit studio pour une cage aux fauves\u2026<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p><a href=\"https:\/\/video.union.fr\/thematiques\/reveil-coquin\"><div class=\"wrap-img\" id=\"wrap-img-415796\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-415796 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2023\/07\/widget_vod_reveil_coquin-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p>(Photo \u00e0 la une : <em>Getty Images<\/em>)<\/p> <p><strong>A lire aussi :<\/strong><\/p> <p><a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-prime-et-stagiaires-260583.html#post-260583\">La prime et les stagiaires<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-forme-par-la-stagiaire-366564.html#post-366564\">Form\u00e9 par la stagiaire<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-de-la-cougar-au-chaton-152099.html#post-152099\">De la cougar au chaton<\/a><\/p> ","protected":false},"excerpt":{"rendered":"<p>Rick commence dans la vie active. Sur son trajet, il voit souvent une femme v\u00eatu comme une panth\u00e8re. Un jour, le jeune homme deviendra sa proie !<\/p>\n","protected":false},"author":7,"featured_media":445716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5951,5938,5949,5,2,8],"tags":[3257,1207,109,7657,250,7658],"class_list":["post-279810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-histoire-de-sexe-cougar-milf-recits","category-fellation-recits","category-infidelite-adultere-recits","category-menu_site","category-mise-en-avant","category-recits","tag-amante","tag-cougar","tag-fellation","tag-leopard","tag-milf","tag-predatrice"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/279810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=279810"}],"version-history":[{"count":5,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/279810\/revisions"}],"predecessor-version":[{"id":445715,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/279810\/revisions\/445715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/445716"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=279810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=279810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=279810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}