{"id":296887,"date":"2019-09-04T18:09:25","date_gmt":"2019-09-04T16:09:25","guid":{"rendered":"http:\/\/www.union.fr\/?p=296887"},"modified":"2019-09-04T18:09:25","modified_gmt":"2019-09-04T16:09:25","slug":"vulves-parfaites-nexistent","status":"publish","type":"post","link":"https:\/\/www.union.fr\/actus\/buzz\/vulves-parfaites-nexistent-296887.html","title":{"rendered":"\u00ab\u00a0Viva la vulva\u00a0\u00bb, la c\u00e9l\u00e9bration des vulves par Nana"},"content":{"rendered":"<p>Un sexe f\u00e9minin sans poil et sans rien qui d\u00e9passe\u00a0: le culte de la vulve \u00ab\u00a0parfaite\u00a0\u00bb cultiv\u00e9e par la pornographie n\u2019en finirait pas de complexer les femmes. Pour cause, certaines femmes auraient recours \u00e0 la chirurgie de leurs l\u00e8vres vaginales, notamment des mineures : 200 filles britanniques de moins de 18 ans, ainsi que 150 filles de moins de 15 ans auraient subi une labiaplastie, comme cit\u00e9 dans un article du BBC.<\/p> <p>\u00ab\u00a0Je vois des jeunes filles de 11, 12 ou 13 ans qui pensent que quelque chose ne va pas dans leur vulve &#8211; qu\u2019elles ne sont pas de la bonne forme, qu\u2019elles ne sont pas de la bonne taille et qu\u2019elles expriment presque le d\u00e9go\u00fbt.\u00a0\u00bb explique le m\u00e9decin g\u00e9n\u00e9raliste, Paquita de Zulueta.<\/p> <h2>\u00ab\u00a0La seule vulve parfaite, c\u2019est la v\u00f4tre\u00a0!\u00a0\u00bb<\/h2> <p>En r\u00e9ponse Nana lancerait <a href=\"https:\/\/www.aufeminin.com\/news-societe\/viva-la-vulva-la-campagne-nana-qui-brise-le-tabou-autour-du-sexe-feminin-s4003817.html\">sa nouvelle campagne \u00ab\u00a0viva la vulva\u00a0\u00bb pour c\u00e9l\u00e9brer toutes les vulves<\/a>.<\/p> <p>Elle pr\u00f4nerait la diversit\u00e9 des vulves \u00e0 travers un clip aussi cr\u00e9atif que p\u00e9dagogique. Nana conforterait les femmes \u00e0 ressentir de la fiert\u00e9, \u00e0 d\u00e9faut de ce sentiment de honte et de g\u00eane\u00a0: \u00ab\u00a0Des poils pubiens \u00e0 la taille des l\u00e8vres, nous voulons que vous soyez fi\u00e8res de ce que vous avez.\u00a0\u00bb<\/p> <p>Nana veut faire passer le message qu\u2019aucune vulve n\u2019est \u00ab\u00a0parfaite\u00a0\u00bb Elles sont toutes uniques, grandes ou petites, claires ou fonc\u00e9es, \u00e9pil\u00e9es ou poilues, \u00ab\u00a0les diff\u00e9rences doivent \u00eatre c\u00e9l\u00e9br\u00e9es\u00a0\u00bb ajoute Nana.<\/p> <p>Nana ne s\u2019arr\u00eaterait pas l\u00e0, elle pr\u00e9senterait leur exposition aussi baptis\u00e9e \u00ab\u00a0viva la vulva\u00a0\u00bb autour de cinq th\u00e8mes du 20 au 22 septembre. \u00ab\u00a0La diversit\u00e9 des femmes et de leurs vulves sera mise \u00e0 l\u2019honneur, sous le regard affut\u00e9 de Laura Stromboni \u2013 cr\u00e9atrice du compte Instagram MyDearVagina\u00a0\u00bb, affirme <a href=\"http:\/\/le-chat-perche.ch\/evenements\/viva-la-vulva\/?fbclid=IwAR1wd9--eKgif5omL-NxIJQTGIAf1rswKZ8LP-sRV941xinDhWW8K8l4uNc\">le Chat perch\u00e9, un site regroupant diverses expositions<\/a>.<\/p> <p><iframe loading=\"lazy\" title=\"VIVA LA VULVA\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/0k-_4WloY6Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p> <p><strong>\u00c0 lire aussi\u2026<\/strong><\/p> <p><a href=\"http:\/\/www.union.fr\/sexo\/comprendre-sa-sexualite\/sautoexplorer-chatte-moyen-de-sapprivoiser-293696.html\">Mesdames, il est temps de s&rsquo;auto-explorer le sexe !<\/a><\/p> <p><a href=\"http:\/\/www.union.fr\/actus\/les-breves\/insolite\/the-perfect-v-marque-scandinave-lace-enlumineur-pour-la-vulve-174358.html\">The perfect V : une marque scandinave lance un enlumineur pour la vulve<\/a><\/p> <p><a href=\"http:\/\/www.union.fr\/sexo\/corps-travaux-joies-chirurgie-plastique-187206.html\">Jusqu&rsquo;o\u00f9 peut-on aller en mati\u00e8re de chirurgie plastique ?<\/a><\/p> ","protected":false},"excerpt":{"rendered":"<p>Chaque vulve est unique et doit \u00eatre c\u00e9l\u00e9brer, ce que ferait Nana dans sa nouvelle campagne. Un moyen de briser les diktats de la soci\u00e9t\u00e9 et de la pornographie de la vulve \u00ab\u00a0parfaite\u00a0\u00bb&#8230;<\/p>\n","protected":false},"author":11696,"featured_media":296891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,3,5],"tags":[578,4019,3011,4879,5568,2156],"class_list":["post-296887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buzz","category-diaporama-accueil","category-menu_site","tag-campagne","tag-celebration","tag-chirurgie","tag-levres","tag-nana","tag-vulve"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/296887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/11696"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=296887"}],"version-history":[{"count":3,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/296887\/revisions"}],"predecessor-version":[{"id":297032,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/296887\/revisions\/297032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/296891"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=296887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=296887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=296887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}