{"id":342885,"date":"2021-01-28T14:10:13","date_gmt":"2021-01-28T12:10:13","guid":{"rendered":"https:\/\/www.union.fr\/?p=342885"},"modified":"2021-01-26T18:49:04","modified_gmt":"2021-01-26T16:49:04","slug":"sexe-contre-covid19","status":"publish","type":"post","link":"https:\/\/www.union.fr\/sexo\/sexe-contre-covid19-342885.html","title":{"rendered":"Le sexe contre le Covid-19 ?"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\"> <div class=\"section\"> <div class=\"layoutArea\"> <div class=\"column\"> <p><em>Ma copine et moi faisons partie des couples qui ont bien v\u00e9cu le confinement. Et m\u00eame tr\u00e8s bien sur le plan sexuel. Nous nous sommes racont\u00e9s nos fantasmes et nous les avons explor\u00e9s. Nous baisions facilement deux fois par jour. Alors comme faire l\u2019amour d\u00e9veloppe des anticorps et favorise la sant\u00e9, je me demandais si nous n\u2019\u00e9tions pas immunis\u00e9s, puisque nous p\u00e9tons la forme ?<\/em><\/p> <\/div> <div class=\"page\" title=\"Page 1\"> <div class=\"section\"> <div class=\"layoutArea\"> <div class=\"column\"> <p>Vous faites donc partie, et c\u2019est tant mieux pour vous, des couples heureux chez qui<a href=\"https:\/\/www.union.fr\/actus\/reconfinement-regain-de-libido-francais-339269.html\"> le confinement<\/a> a eu des <a href=\"https:\/\/www.union.fr\/actus\/insolite\/sexe-bienfaits-benefiques-sante-312984.html\">effets b\u00e9n\u00e9fiques<\/a> et je tiens \u00e0 vous en f\u00e9liciter. Vous avez raison de penser qu\u2019une sexualit\u00e9 active\u00a0et \u00e9panouie est un facteur d\u2019\u00e9quilibre de la sant\u00e9, \u00e0\u00a0la fois mentale et physique, comme l\u2019ont prouv\u00e9 plu- sieurs \u00e9tudes scientifiques. L&rsquo;acte sexuel est en effet bon pour la forme et pour la t\u00eate, notamment gr\u00e2ce aux endorphines.<\/p> <p>En revanche, je tiens \u00e0 le pr\u00e9ciser, et j\u2019insiste fortement sur ce point, vous faites une grave erreur de fond en pensant que faire l\u2019amour fait augmenter la production d\u2019anticorps.<\/p> <p>L\u2019amour, et l\u2019orgasme en particulier, stimulent la fabrication et\u00a0la lib\u00e9ration de nombreuses hormones et neurom\u00e9diateurs, utiles \u00e0 la r\u00e9gulation de notre \u00e9nergie vitale et de notre humeur, avec pour corollaire une action positive sur de nombreux organes. Le sexe peut \u00e9galement agir sur le stress et serait un <a href=\"https:\/\/www.union.fr\/sexo\/sexe-anti-douleur-342618.html\">excellent antalgique<\/a>, notamment contre les douleurs des migraines ou des menstruation.<\/p> <p>Il est cependant hors de propos d&rsquo;affirmer que cela puisse vous prot\u00e9ger de l\u2019\u00e9pid\u00e9mie actuelle et il est compl\u00e8tement erron\u00e9 de croire que vous puissiez \u00eatre immunis\u00e9s. Rappelons-le, seuls la distanciation sociale et le respect des gestes barri\u00e8res, peuvent prot\u00e9ger de la contamination par le virus du COVID-19.<\/p> <p>Par ailleurs, et cela est vrai pour toutes\u00a0les maladies contagieuses, l\u2019immunit\u00e9 ne peut pas s\u2019acqu\u00e9rir sans attraper la maladie elle-m\u00eame hormis la possibilit\u00e9 de se faire vacciner, ce qui n\u2019est toujours pas possible pour ce coronavirus.<\/p>  <p><strong>A LIRE AUSSI :\u00a0<\/strong><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/coronavirus-sexuellement-transmissible-332173.html\">Le coronavirus est-il sexuellement transmissible ?\u00a0<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/fantasme-exterieur-confinement-342602.html\">Je r\u00eave de faire l&rsquo;amour en ext\u00e9rieur, est-ce d\u00fb au confinement ?\u00a0<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/342817-342817.html\">Le sexe contre l&rsquo;acn\u00e9 : v\u00e9rit\u00e9 ou id\u00e9e re\u00e7ue ?\u00a0<\/a><\/p>  <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> ","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est reconnu depuis longtemps, la science pr\u00eate de nombreux bienfaits au sexe : anti-stress, anti-douleur, bon pour la forme et pour le moral mais est-il aussi efficace contre le virus ? <\/p>\n","protected":false},"author":7,"featured_media":342908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,36,5,2,29,15,27],"tags":[1145,6188,6189,6190,2336],"class_list":["post-342885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-maladies-et-sexualite","category-menu_site","category-mise-en-avant","category-nos-conseils-dexperts","category-sexo","category-sexualite-et-sante","tag-bienfaits","tag-covid19","tag-immunite","tag-question-de-sexe","tag-sexo"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/342885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=342885"}],"version-history":[{"count":4,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/342885\/revisions"}],"predecessor-version":[{"id":342911,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/342885\/revisions\/342911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/342908"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=342885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=342885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=342885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}