{"id":355131,"date":"2021-05-26T14:00:47","date_gmt":"2021-05-26T12:00:47","guid":{"rendered":"https:\/\/www.union.fr\/?p=355131"},"modified":"2021-05-25T10:07:01","modified_gmt":"2021-05-25T08:07:01","slug":"tout-savoir-sur-le-candaulisme-de-lhistoire-a-la-pratique","status":"publish","type":"post","link":"https:\/\/www.union.fr\/sexo\/tout-savoir-sur-le-candaulisme-de-lhistoire-a-la-pratique-355131.html","title":{"rendered":"Tout savoir sur le candaulisme : De l&rsquo;histoire \u00e0 la pratique"},"content":{"rendered":"<h2 style=\"text-align: left;\">Un peu de terminologie<\/h2> <p>Dans son ouvrage (culte), Eve de Candaulie \u00e9crit\u00a0:<em> \u00ab\u00a0Le candaulisme, c\u2019est de l\u2019infid\u00e9lit\u00e9 consentie et organis\u00e9e.\u00a0\u00bb<\/em><\/p> <p>Il y a une quinzaine d\u2019ann\u00e9e, peu de gens connaissaient le terme de <a href=\"https:\/\/www.union.fr\/actus\/interviews\/candaulisme-milene-leroy-sexotherapeute-152760.html\">candaulisme<\/a> (cuckolding en anglais).<span class=\"Apple-converted-space\" >\u00a0 <\/span>Il s\u2019agit d\u2019une pratique de couple o\u00f9 l\u2019homme (plus rarement la femme) prend du plaisir \u00e0 regarder sa compagne coucher avec un ou plusieurs partenaires. Quant \u00e0 elle, c\u2019est le plaisir de s\u2019envoyer en l\u2019air avec d\u2019autres devant son compagnon. Cette pratique est un peu plus complexe qu\u2019un simple jeu d\u2019exhibitionnisme et de voyeurisme.<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>On y associe \u00e9galement l\u2019id\u00e9e de \u00ab\u00a0cocufier\u00a0\u00bb son partenaire. Dans les milieux BDSM (mais pas que), il s\u2019agit aussi d\u2019humilier le mari voyeur comme l\u2019explique Cathy\u00a0:<\/p> <p>\u00ab<em>\u00a0Le jeu du mari cocu nous excite autant l\u2019un que l\u2019autre. J\u2019adore insulter ou humilier mon mari quand je me fais prendre devant lui. \u00c7a peut \u00eatre des phrases comme\u00a0: regarde comme il me baise bien lui avec sa grosse queue alors que toi, tu es incapable de me satisfaire et de me faire jouir.\u00a0\u00bb<\/em><\/p> <p>Cette relation <a href=\"https:\/\/www.union.fr\/sexo\/nos-conseils-dexperts\/est-ce-normal-detre-content-alors-que-ma-femme-couche-avec-un-autre-14163.html\">d\u2019adult\u00e8r<\/a>e consenti peut se faire en dehors de la pr\u00e9sence du mari. La femme couche avec son ou ses amants sans voyeurisme mais g\u00e9n\u00e9ralement, lorsqu\u2019elle retrouve son compagnon, elle lui raconte tout de sa partie de jambes en l\u2019air. <span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>Au terme de candaulisme s\u2019est ajout\u00e9 celui de housewyfe, une femme mari\u00e9e et volage encourag\u00e9e par son mari de se savoir cocu et fier de savoir qu\u2019elle s\u2019\u00e9panouie dans les bras d\u2019autres partenaires. Ces partenaires sont souvent appel\u00e9s Bull dominants ou Alpha dominants, des taureaux, des \u00e9talons souvent rechercher pour leur vigueur et leurs prouesses sexuelles comme l\u2019explique Cathy\u00a0:<\/p> <p><em>\u00ab\u00a0Avec mes amants, ce n\u2019est que du sexe. Il nous arrive bien s\u00fbr de boire un verre ensemble apr\u00e8s nous \u00eatre envoy\u00e9s en l\u2019air mais ce que je leur demande avant tout, c\u2019est qu\u2019il me baise bien devant mon mari, qu\u2019il me fasse crier, qu\u2019ils me fassent jouir \u00e0 plusieurs reprises. Je revois parfois certains d\u2019entre eux, uniquement ceux qui ont su me satisfaire pleinement sur le plan sexuel.\u00a0\u00bb<span class=\"Apple-converted-space\" >\u00a0<\/span><\/em><\/p> <h2>Un peu d\u2019histoire et quelques chiffres<\/h2> <p>Le terme de candaulisme nous vient du roi semi-l\u00e9gendaire de Lydie, Candaule, qui v\u00e9cut au VIIIe si\u00e8cle avant J-C. Il \u00e9tait mari\u00e9 \u00e0 une tr\u00e8s belle femme, si belle et si d\u00e9sirable qu\u2019il vantait chaque jour le pouvoir \u00e9rotique qu\u2019elle d\u00e9gageait \u00e0 l\u2019un des officiers de sa garde Gyg\u00e8s dans un inique but\u00a0: convaincre ce dernier d\u2019aller d\u00e9couvrir les charmes de la reine, le soir lorsqu\u2019elle se d\u00e9shabillait.<span class=\"Apple-converted-space\" >\u00a0 <\/span>Candaule, c\u2019est aussi le pseudonyme du cr\u00e9ateur du site candaulisme.com et qui a \u00e9t\u00e9 le premier faire r\u00e9f\u00e9rence au roi de Lydie et \u00e0 associer le terme de candaulisme \u00e0 cette pratique.<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>Alors qu\u2019en 2004, le terme n\u2019apparaissait pas encore dans les requ\u00eates en ligne, d\u00e8s 2010 le terme avait d\u00e9pass\u00e9 celui de libertinage dans le total des recherches. Et des chiffres qui ne cessent d\u2019exploser depuis 2016.<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>Plus r\u00e9v\u00e9lateur encore, depuis 2017, ce sont les films li\u00e9s \u00e0 ce th\u00e8me qui progresse le plus dans le trafic du site Pornhub. Dans son livre La vulve, la verge et le clito, Ma\u00efa Mazaurette cite une \u00e9tude am\u00e9ricaine qui r\u00e9v\u00e8le que plus de 50% des hommes ont des fantasmes li\u00e9s au candaulisme et un tiers des femmes. Etonnant\u2026<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p>Sur la quasi-totalit\u00e9 des sites de <a href=\"https:\/\/www.union.fr\/sexo\/libertinage\/rencontres-sur-un-site-libertin-un-phenomene-de-societe-349576.html\">rencontres libertines<\/a> la progression du nombre de couples ayant ajout\u00e9 le candaulisme dans leurs recherches d\u2019exp\u00e9riences sexuelles souhait\u00e9es de cesse de s\u2019accroitre. Tout comme celle des hommes \u00ab\u00a0cocufieurs\u00a0\u00bb.<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p> <p><a href=\"https:\/\/www.union.fr\/actus\/interviews\/interview-pros-du-sexe\/le-plaisir-feminin-selon-maia-mazaurette-351181.html\">Ma\u00efa Mazaurette<\/a> avoue elle-m\u00eame que le plus grand nombre de questions qui lui sont pos\u00e9es par ses lecteurs concerne ce th\u00e8me.<span class=\"Apple-converted-space\" >\u00a0 <\/span>Mode, nouvelle tendance, \u00e9volution de nos m\u0153urs et des relations li\u00e9es \u00e0 la fid\u00e9lit\u00e9 dans le couple, acceptation d\u2019un tabou\u00a0? Tous ces chiffres ont de quoi nous interroger\u2026<span class=\"Apple-converted-space\" >\u00a0<\/span><\/p>  <p><strong>A LIRE AUSSI :\u00a0<\/strong><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/libertinage\/candaulisme-reponse-sexologue-355032.html\">Tout savoir sur le candaulisme : les r\u00e9ponses d&rsquo;une sexologue\u00a0<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/les-pratiques-sexuelles\/petite-histoire-du-candaulisme-152725.html\">Petite histoire du candaulisme\u00a0<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/sexo\/les-pratiques-sexuelles\/candaulisme-conseils-debutant-317527.html\">Candaulisme : nos conseils pour ceux qui veulent se lancer !\u00a0<\/a><\/p>  ","protected":false},"excerpt":{"rendered":"<p>Ce samedi 5 juin \u00e0 minuit, la cha\u00eene Canal + diffuse \u00ab\u00a0Candaulisme, mon amour\u00a0\u00bb.  Parmi le courrier abondant re\u00e7u chaque mois beaucoup concerne le candaulisme. La diffusion du film labellis\u00e9 Union est une jolie occasion de vous en dire un peu plus sur cette pratique. Revenons aux bases : le candaulisme, c&rsquo;est quoi et \u00e7a vient d&rsquo;ou ? <\/p>\n","protected":false},"author":7,"featured_media":355182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5790,5,2,31,15],"tags":[1149,508,509],"class_list":["post-355131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-libertinage","category-menu_site","category-mise-en-avant","category-les-pratiques-sexuelles","category-sexo","tag-adultere","tag-candaulisme","tag-libertinage"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/355131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=355131"}],"version-history":[{"count":1,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/355131\/revisions"}],"predecessor-version":[{"id":355183,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/355131\/revisions\/355183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/355182"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=355131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=355131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=355131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}