{"id":387095,"date":"2022-04-22T12:00:46","date_gmt":"2022-04-22T10:00:46","guid":{"rendered":"https:\/\/www.union.fr\/?p=387095"},"modified":"2022-04-20T16:39:02","modified_gmt":"2022-04-20T14:39:02","slug":"chirurgie-de-vulve-nouvelle-mode-dangereuse","status":"publish","type":"post","link":"https:\/\/www.union.fr\/actus\/chirurgie-de-vulve-nouvelle-mode-dangereuse-387095.html","title":{"rendered":"Chirurgie de la vulve : une nouvelle mode dangereuse !"},"content":{"rendered":"<p>La chirurgie esth\u00e9tique existe pour toutes les parties du corps : pommettes, nez, hanches, seins, fesses et maintenant la <a href=\"https:\/\/www.union.fr\/actus\/fusee-forme-de-vulve-allemagne-cest-possible-384157.html#post-384157\">vulve<\/a>. De plus en plus de Fran\u00e7aises modifient leur vulve : <strong>Pourquoi ? Est-ce dangereux ?<\/strong> On vous explique !<\/p> <p><a href=\"http:\/\/boutique.union.fr\/\"><div class=\"wrap-img\" id=\"wrap-img-367679\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"size-medium wp-image-367679 aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/09\/4-1-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <h2>L&rsquo;esth\u00e9tisme avant tout<\/h2> <p>Cette op\u00e9ration ne concerne pas un aspect sanitaire mais bel et bien <strong>un pr\u00e9tendu manque d&rsquo;esth\u00e9tisme<\/strong> de la <a href=\"https:\/\/www.union.fr\/actus\/instant-culture-vulves-et-livres-erotiques-la-selection-de-juin-357265.html#post-357265\">vulve<\/a>. En 2010,\u00a0 1839 femmes avaient eu recours \u00e0 une nymphoplastie ou \u00ab\u00a0<em>lifting de la vulve<\/em>\u00ab\u00a0, <strong>en 2019 cette op\u00e9ration a \u00e9t\u00e9 pratiqu\u00e9e 4772 fois (principalement sur des jeunes femmes entre 18 et 30 ans).<\/strong><\/p> <p>Maeva Ghennam, c\u00e9l\u00e8bre candidate des \u00ab\u00a0<em>Marseillais<\/em>\u00a0\u00bb faisait la promotion de cette <a href=\"https:\/\/www.union.fr\/sexo\/comment-retrouver-de-beaux-seins-sans-chirurgie-14802.html#post-14802\">chirurgie <\/a>vulvaire : \u00ab\u00a0<em>Pour moi c\u2019est super important d\u2019avoir un beau vagin, <strong>moi j\u2019ai de la chance j\u2019ai trop un beau <a href=\"https:\/\/www.union.fr\/sexo\/vagin-borgne-malformation-de-lve-382764.html#post-382764\">vagin<\/a><\/strong>, genre j\u2019ai pas les l\u00e8vres qui pendent mais il faut entretenir et mon docteur c\u2019est le meilleur pour \u00e7a. <strong>Genre l\u00e0 c&rsquo;est comme si j\u2019avais douze ans\u00a0!<\/strong><\/em>\u00a0\u00bb<\/p> <p>Les propos de la jeune femme n&rsquo;ont pas manqu\u00e9 de choquer, que cela soit par l&rsquo;aspect d\u00e9rangeant d&rsquo;avoir \u00ab\u00a0<em>un beau vagin<\/em>\u00a0\u00bb et donc de consid\u00e9rer qu&rsquo;il y en a des moches ou que<strong> le suppos\u00e9 \u00ab\u00a0<em>beau vagin<\/em>\u00a0\u00bb soit celui d&rsquo;une enfant de 12 ans&#8230;<\/strong><\/p> <p><a href=\"https:\/\/video.union.fr\/premier-casting\/premier-casting-crystal\"><div class=\"wrap-img\" id=\"wrap-img-384746\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-384746 aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/02\/3-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <h2>Une op\u00e9ration dangereuse ?<\/h2> <p>La nymphoplastie comporte deux risques majeurs :<\/p> <ul> <li>sur la sant\u00e9 <strong>physique<\/strong><\/li> <li>sur la sant\u00e9 <strong>mentale<\/strong><\/li> <\/ul> <p>Pour la sant\u00e9 physique, le risque principal pourrait \u00eatre <strong>une perte de sensations durant les rapports sexuels et des douleurs.<\/strong> Cette op\u00e9ration causerait \u00e9galement des troubles psychologiques. <strong>La dysmorphophobie ?<\/strong> Il s&rsquo;agit de l&rsquo;obsession des d\u00e9fauts <a href=\"https:\/\/www.union.fr\/actus\/phobie-envers-les-lgbt-des-impacts-physiques-et-psychologiques-consequents-295146.html#post-295146\">physiques<\/a>. Les personnels de sant\u00e9 pratiquant ce type d&rsquo;op\u00e9ration doivent pr\u00e9venir leurs patientes qu&rsquo;il n&rsquo;existe pas de \u00ab\u00a0<em>vagin disgracieux<\/em>\u00ab\u00a0. La taille des <a href=\"https:\/\/www.union.fr\/sexo\/nos-conseils-dexperts\/femme\/existe-t-il-une-operation-permettant-de-reduire-la-taille-des-grandes-levres-14332.html#post-14332\">l\u00e8vres<\/a>, leur \u00e9paisseur, leur couleur, etc. ne jouent pas de r\u00f4le sur la sexualit\u00e9.<\/p> <p><em>\u00ab\u00a0tr\u00e8s sinc\u00e8rement, c\u2019est ne pas connaitre l\u2019anatomie humaine :\u00a0<strong>il n\u2019y a aucune corr\u00e9lation entre les l\u00e8vres et l\u2019innervation du clitoris et du vagin<\/strong>.\u00a0Cette derni\u00e8re est tr\u00e8s profonde tandis que les l\u00e8vres sont externes et superficielles.\u00a0\u00bb <\/em>explique le chirurgien Yohann Derhy dans Sant\u00e9 Magazin<em>e.<\/em><\/p> <p><a href=\"https:\/\/livecam.union.fr\/fr\/\"><div class=\"wrap-img\" id=\"wrap-img-373776\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-373776 aligncenter\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/11\/2-1-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <h2>L&rsquo;origine de la vulve dite \u00ab\u00a0<em>parfaite<\/em>\u00ab\u00a0<\/h2> <p>Les origines de ce culte du \u00ab\u00a0<em>vagin parfait<\/em>\u00a0\u00bb (ndlr. comprendre : un vagin \u00e9troit et une vulve aux l\u00e8vres ferm\u00e9es et ras\u00e9es) font encore d\u00e9bat.<\/p> <p><strong>Certains attribuent cette mode au <a href=\"https:\/\/www.union.fr\/actus\/regarder-porno-devient-metier-386720.html#post-386720\">porno<\/a><\/strong> comme OsezLeF\u00e9minisme : \u00ab\u00a0<em>Attaquons nous plut\u00f4t au patriarcat, et au <strong>porno qui a impos\u00e9 l&rsquo;\u00e9pilation int\u00e9grale du sexe aux filles et aux femmes<\/strong>, qui nous pousse \u00e0 d\u00e9tester nos vulves et nos l\u00e8vres. Le porno qui pr\u00e9sente comme mod\u00e8le de vulve baisable une vulve qui ressemble \u00e0 celle d&rsquo;une fille pr\u00e9pub\u00e8re<\/em>\u00ab\u00a0.<\/p> <p>D&rsquo;autres d\u00e9fendent l&rsquo;<a href=\"https:\/\/www.union.fr\/actus\/actrice-porno-lapres-carriere-mouvemente-386469.html#post-386469\">industrie pornographique <\/a>comme Ludivine Demol, chercheuse doctorante \u00e0 Paris 8 : \u00ab\u00a0<em><strong>Dans le porno comme ailleurs, il existe autant de formes de vulves que de types d&rsquo;\u00e9pilation.<\/strong> Si le probl\u00e8me venait de lui, on aurait d\u00e9j\u00e0 observ\u00e9 une hausse des op\u00e9rations chez les actrices<\/em>\u00a0\u00bb d\u00e9clare-t-elle dans Madame Le Figaro.<\/p> <p>Il n&rsquo;existe pas de vulve \u00ab\u00a0<em>normale<\/em>\u00ab\u00a0. Le premier \u00e9pisode des\u00a0<em>\u00ab\u00a0Principes du plaisir<\/em>\u00a0\u00bb (sur Netflix) se consacre enti\u00e8rement \u00e0 l&rsquo;acceptation de son corps et passe en revu les principaux clich\u00e9s sur le corps f\u00e9minin. En t\u00eate de liste : <strong>la vulve et ses multiples apparences.<\/strong><\/p> <p><strong>A lire aussi :<\/strong><\/p> <p><a href=\"https:\/\/www.union.fr\/actus\/senvoyer-lair-lespace-astronautes-mystere-plane-294818.html#post-294818\">S\u2019envoyer en l\u2019air\u2026 ou dans l\u2019espace pour les astronautes : un myst\u00e8re plane<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/actus\/buzz\/pornhub-le-projet-dun-film-porno-dans-lespace-144706.html#post-144706\">Pornhub, le projet d\u2019un film porno dans l\u2019espace<\/a><\/p> <p><a href=\"https:\/\/www.union.fr\/actus\/sante-test-revolutionnaire-lendometriose-382132.html#post-382132\">Sant\u00e9 : un test r\u00e9volutionnaire pour l\u2019endom\u00e9triose !<\/a><\/p> ","protected":false},"excerpt":{"rendered":"<p>De plus en plus de Fran\u00e7aises ont recours au lifting de la vulve. Quelles sont les raisons ? Est-ce dangereux ? On vous explique tout !<\/p>\n","protected":false},"author":15371,"featured_media":387102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,37,3,5,2,15,27],"tags":[3011,1657,2156],"class_list":["post-387095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","category-chirurgie-et-sexualite","category-diaporama-accueil","category-menu_site","category-mise-en-avant","category-sexo","category-sexualite-et-sante","tag-chirurgie","tag-sante","tag-vulve"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/387095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/15371"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=387095"}],"version-history":[{"count":3,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/387095\/revisions"}],"predecessor-version":[{"id":387184,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/387095\/revisions\/387184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/387102"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=387095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=387095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=387095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}