{"id":434004,"date":"2024-02-01T14:30:54","date_gmt":"2024-02-01T12:30:54","guid":{"rendered":"https:\/\/www.union.fr\/?p=434004"},"modified":"2024-02-01T15:11:26","modified_gmt":"2024-02-01T13:11:26","slug":"histoire-de-sexe-mon-fantasme-sur-les-grosses-bites-union","status":"publish","type":"post","link":"https:\/\/www.union.fr\/recits\/histoire-de-sexe-mon-fantasme-sur-les-grosses-bites-union-434004.html","title":{"rendered":"Mon fantasme sur les grosses bites!"},"content":{"rendered":"<h2 class=\"p1\">Voyant voyeur<\/h2> <p class=\"p3\">Par ces lumi\u00e8res tristes de l\u2019hiver, je prends plaisir \u00e0 regarder des photos de vacances o\u00f9 le soleil brille. Je suis tomb\u00e9e sur celles de cette escapade et le souvenir est si chaud pour moi, que je vais vous le partager. Voici mon histoire sexe. Je vous raconte mon <a href=\"https:\/\/www.union.fr\/recits\/la-petite-allumeuse-14127.html\">histoire de sexe.<\/a><\/p>  <p><a href=\"https:\/\/boutique.union.fr\/\"><div class=\"wrap-img\" id=\"wrap-img-367678\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"aligncenter wp-image-367678 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/09\/3-1-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p class=\"p3\">L\u2019\u00e9t\u00e9 dernier nous sommes partis dans les Canaries avec Fab, mon petit ami. Nous voulions du temps et de l\u2019espace pour nous envoyer en l\u2019air, nous adorons baiser en ext\u00e9rieur. C\u2019\u00e9tait le troisi\u00e8me jour, en promenade semi -romantique, semi- \u00e9rotique (mon copain n\u2019arr\u00eatait pas de me tripoter et de me raconter des trucs cochons). Nous avons d\u00e9bouch\u00e9 sur une petite clairi\u00e8re ensoleill\u00e9e, nous nous y sommes allong\u00e9s pour profiter de l\u2019astre br\u00fblant en nous caressant tendrement. <strong>Il avait soulev\u00e9 mon d\u00e9bardeur et j\u2019avais les seins nus pour finir par d\u00e9grafer le bouton de mon mini short en jean et glisser sa main jusqu\u2019\u00e0 ma fente qui s\u2019est mise \u00e0 mouiller \u00e0 flots.<\/strong><\/p>  <p class=\"p3\">Je commen\u00e7ais \u00e0 g\u00e9mir tout en t\u00e2tant<a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-notre-jouet-sexuel-364206.html\"> sa queue<\/a> quand un bruit de bois sec qu\u2019on casse nous a fait nous relever d\u2019un coup\u00a0! <strong>L\u00e0, \u00e0 quelques m\u00e8tres de nous, un grand type en tee-shirt noir \u00e9tait en train de nous mater en se branlant.<\/strong> J\u2019allais crier lorsque j\u2019ai entendu, estomaqu\u00e9e, Fab lui dire bonjour en espagnol, tout sourire\u00a0! J\u2019\u00e9tais \u00e9berlu\u00e9e, lui qui est d\u2019un naturel hyper jaloux, cela ne lui faisait rien qu\u2019un inconnu reluque mes nibards\u00a0! Le gars s\u2019est avanc\u00e9, son visage \u00e9tait juv\u00e9nile, il ne devait pas avoir plus de la vingtaine, il n\u2019avait m\u00eame pas de barbe. Rouge comme une pivoine, il a l\u00e2ch\u00e9 son sexe qui est rest\u00e9 raide comme un monolithe, j\u2019ai ouvert des yeux larges comme des soucoupes\u00a0! Mon Dieu, ce jeune homme \u00e9tait mont\u00e9 tel un \u00ab\u00a0burro\u00a0\u00bb, un \u00e2ne en espagnol.<strong> Mon compagnon sait que je fantasme grave sur les grosses bites, mais l\u00e0, cela d\u00e9passait l\u2019entendement, le gland lui arrivait presque \u00e0 la hauteur du nombril\u00a0!<\/strong><\/p>  <p><a href=\"https:\/\/boutique.union.fr\/\"><div class=\"wrap-img\" id=\"wrap-img-367684\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-367684 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/09\/9-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p class=\"p3\"><strong>\u00ab\u00a0Allez, suce-le si tu en as envie, mais juste une pipe hein\u00a0? Pour le reste, il n\u2019y a que moi qui te baise\u00a0!\u00a0\u00bb<\/strong><\/p> <p class=\"p3\">J\u2019ai h\u00e9sit\u00e9 cinq secondes, toutes ces nouveaut\u00e9s dans mon couple, cela allait trop vite pour moi, mais Fab me souriait, l\u2019autre, qui avait ressaisi son machin en main, restait l\u00e0 comme une statue. Je me suis d\u00e9cid\u00e9e, puisque mon mec \u00e9tait d\u2019accord, autant de pas rater cette opportunit\u00e9. Notre voyeur s\u2019est fig\u00e9 encore un peu plus lorsqu\u2019il m\u2019a regard\u00e9 avancer \u00e0 genoux vers lui, il ne devait pas en revenir\u00a0! Ses yeux brillaient comme s\u2019il avait gagn\u00e9 au loto\u00a0!<\/p> <p class=\"p3\"><strong>J\u2019ai attrap\u00e9 sa grosse bite du bout des doigts et j\u2019ai donn\u00e9 de petits coups de langue timides sur son gland et sur son frein.<\/strong> Le gar\u00e7on s\u2019est enhardi lorsqu\u2019il a rep\u00e9r\u00e9 mon homme en train de prendre des photos de cette sc\u00e8ne totalement surr\u00e9aliste. <strong>Il s\u2019\u00e9tait lui-m\u00eame mis la queue \u00e0 l\u2019air et se branlait tout en me matant sucer un autre que lui\u00a0! Surr\u00e9aliste, vous dis-je\u00a0!<\/strong><\/p>  <p class=\"p3\"><strong>Une main sur ma nuque, il accompagnait mes va-et-vient, me baisant la bouche de plus en plus profond\u00e9ment.<\/strong> Contrairement \u00e0 ce \u00e0 quoi je m\u2019attendais en revanche, il faisait preuve d\u2019une belle r\u00e9sistance, moi qui pensais avoir \u00e0 faire \u00e0 un puceau, il me d\u00e9mentait fort joliment, ne montrant aucun signe de faiblesse. J\u2019ai donc sorti le grand jeu, au point o\u00f9 nous en \u00e9tions, autant aller jusqu\u2019au bout. J\u2019ai stopp\u00e9<a href=\"https:\/\/www.union.fr\/recits\/plus-heureuse-femmes-187603.html\"> ma fellation<\/a> et me suis foutue enti\u00e8rement \u00e0 poil, j\u2019ai caress\u00e9 mes seins et gliss\u00e9 une main sur mon sexe. <strong>J\u2019ai juste donn\u00e9 mes doigts \u00e0 l\u00e9cher \u00e0 monsieur \u00ab\u00a0Bite d\u2019\u00e9l\u00e9phant\u00a0\u00bb, j\u2019ai vu sa queue se soulever plusieurs fois, les saveurs de mon con font le m\u00eame effet \u00e0 Fab, c\u2019est dr\u00f4le.<\/strong><\/p> <p><a href=\"https:\/\/boutique.union.fr\/\"><div class=\"wrap-img\" id=\"wrap-img-367677\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-367677 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2021\/09\/2-1-300x250.png\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p class=\"p3\">Je me suis de nouveau accroupie pour reprendre le gros jouet en \u00e9rection maximale, le bout \u00e9tait en train de couler tellement l\u2019excitation \u00e9tait forte chez ce jeune homme. J\u2019ai pass\u00e9 une langue large sous toute la hampe et commenc\u00e9 enfin \u00e0 branler le manche surdimensionn\u00e9. Lorsque je me suis allong\u00e9e, les cuisses totalement \u00e9cart\u00e9es,<strong> j\u2019ai entendu r\u00e2ler mon vicieux photographe.<\/strong> J\u2019ai lanc\u00e9 un coup d\u2019\u0153il, il n\u2019avait pas r\u00e9sist\u00e9 et \u00e9jaculait, balan\u00e7ant ses longs jets cr\u00e9meux dans l\u2019herbe haute.<strong> Mon amant furtif a lui aussi tourn\u00e9 la t\u00eate et la jouissance de mon homme a d\u00e9clench\u00e9 la sienne.<\/strong> J\u2019ai senti l\u2019\u00e9norme gourdin \u00eatre poss\u00e9d\u00e9 de soubresauts, j\u2019ai dard\u00e9 ma langue sur le m\u00e9at et j\u2019ai re\u00e7u la premi\u00e8re bord\u00e9e, puissante, onctueuse. <strong>Elle a enti\u00e8rement recouvert mon palais.Reprenant sa queue \u00e0 la main, le bel inconnu s\u2019est branl\u00e9 pour l\u00e2cher les gicl\u00e9es suivantes.<\/strong> Il y en a eu trop pour que je les compte,<strong><a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-mon-mari-est-naturiste-dans-lame-union-13360.html\"> le sperme <\/a>n&rsquo;arr\u00eatait pas d\u2019emplir ma bouche, \u00e7a coulait le long de mon menton, je n\u2019ai pas r\u00e9ussi \u00e0 tout avaler\u00a0!<\/strong><\/p> <p class=\"p3\">Notre voyeur s\u2019en est all\u00e9 comme il \u00e9tait venu, <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-une-femme-jouir-du-cul-union-407222.html\">cul<\/a> nu, il devait avoir abandonn\u00e9 son pantalon non loin de l\u00e0. Fab m&rsquo;a rejointe, il bandait de nouveau, je me suis allong\u00e9e dans l\u2019herbe folle et j\u2019ai ouvert les cuisses,<strong> il m\u2019a bais\u00e9e si fort que j\u2019ai joui deux fois en criant dans cette clairi\u00e8re d\u00e9cid\u00e9ment fertile en \u00e9v\u00e8nements des plus chauds\u00a0!<\/strong><\/p> <p class=\"p3\"> <p><strong>A LIRE AUSSI: <a href=\"https:\/\/www.union.fr\/recits\/souvenir-de-vacances-150774.html\">Souvenir de vacances<\/a><\/strong><\/p> <p><strong>A LIRE AUSSI: <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-une-partie-de-cartes-13395.html\">Une partie de cartes?<\/a><\/strong><\/p> <p><strong>A LIRE AUSSI:<a href=\"https:\/\/www.union.fr\/recits\/camping-deflore-bleu-265004.html\"> Le camping d\u00e9flore bleu<\/a><\/strong><\/p> ","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9t\u00e9 dernier nous sommes partis dans les Canaries avec Fab, mon petit ami. Nous voulions du temps et de l\u2019espace pour nous envoyer en l\u2019air.<\/p>\n","protected":false},"author":19326,"featured_media":433868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,2,8],"tags":[2603,109,2109,167],"class_list":["post-434004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-menu_site","category-mise-en-avant","category-recits","tag-cul","tag-fellation","tag-queue","tag-sperme","google_news_tags-hisoire-de-sexe"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/434004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/19326"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=434004"}],"version-history":[{"count":2,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/434004\/revisions"}],"predecessor-version":[{"id":434118,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/434004\/revisions\/434118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/433868"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=434004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=434004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=434004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}