{"id":436815,"date":"2024-06-04T16:00:05","date_gmt":"2024-06-04T14:00:05","guid":{"rendered":"https:\/\/www.union.fr\/?p=436815"},"modified":"2024-06-03T16:11:13","modified_gmt":"2024-06-03T14:11:13","slug":"histoire-de-sexe-anna-hard-derche","status":"publish","type":"post","link":"https:\/\/www.union.fr\/recits\/histoire-de-sexe-anna-hard-derche-436815.html","title":{"rendered":"Anna : hard derche"},"content":{"rendered":"<p class=\"p1\"><strong>Anna et son mari, Yann, ont une grande passion pour tous les jeux en plein-air\u00a0: exhibition, dogging, sexe \u00e0 plusieurs\u2026 D\u2019ailleurs, ils sont connus sur les plateformes libertines sous le pseudonyme de <em>Coupleexhib07. <\/em>Libertins depuis une dizaine d\u2019ann\u00e9es, ils ont progress\u00e9 tranquillement dans cet univers, mais aujourd\u2019hui, Anna sait vraiment ce qu\u2019elle veut\u00a0: des hommes, des voyeurs et du sperme. Beaucoup de sperme\u00a0! Elle a accept\u00e9 de nous raconter son premier gang-bang dans la nature. Voici mon <a href=\"https:\/\/www.union.fr\/recits\">histoire de sexe<\/a>.<\/strong><\/p> <h2>Un merveilleux gang-bang !<\/h2> <p class=\"p1\">C\u2019\u00e9tait il y a trois ans, en d\u00e9but d\u2019\u00e9t\u00e9. Le couple conna\u00eet <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-un-couple-de-naturiste-union-434122.html#post-434122\">une plage naturiste<\/a> tr\u00e8s bien fr\u00e9quent\u00e9e sur les bords de l\u2019Ard\u00e8che, proche de Vallon-Pont-d\u2019Arc o\u00f9 madame s\u2019est d\u00e9j\u00e0 exhib\u00e9e. <strong>Cette fois, ce sera une tenue ultra sexy,<\/strong> plus que provocante\u00a0: bas r\u00e9sille, talons aiguille, haut de corps moulant avec d\u00e9collet\u00e9 plongeant et\u2026 un plug-bijou gliss\u00e9 entre ses fesses\u00a0: \u00ab\u00a0<em>J\u2019adore \u00e7a, exciter les hommes, les faire bander, leur donner envie de faire des tas de choses avec moi. Et les faire jouir, sentir leur sperme sur ma peau, sur ma langue, dans ma bouche.\u00a0\u00bb<\/em><\/p> <p><a href=\"https:\/\/video.union.fr\/premier-casting\/premier-casting-shanna\"><div class=\"wrap-img\" id=\"wrap-img-413770\"><img loading=\"lazy\" decoding=\"async\" itemprop=\"thumbnailUrl\" class=\"aligncenter wp-image-413770 size-medium\" src=\"https:\/\/www.union.fr\/wp-content\/uploads\/2023\/04\/widget_vod_shanna-300x250.jpg\" alt=\"\" width=\"300\" height=\"250\" \/><\/div><\/a><\/p> <p class=\"p1\">Comment passer inaper\u00e7ue avec une telle tenue\u00a0! Tr\u00e8s vite, en dehors de son mari, ils seront quatre, \u00e0 venir admirer ses jolies courbes. Anna les met en valeur, allume tant qu\u2019elle peut, se caresse\u00a0: \u00ab\u00a0<em>Rien que l\u00e0, j\u2019\u00e9tais d\u00e9j\u00e0 super excit\u00e9e, d\u00e9licieusement tremp\u00e9e entre mes cuisses.\u00a0\u00bb<\/em><\/p> <p class=\"p1\">Pendant qu\u2019elle <a href=\"https:\/\/www.union.fr\/actus\/interviews\/ils-aiment-exhiber-et-ils-temoignent-435434.html#post-435434\">s\u2019exhibe<\/a>, un peu en retrait de la plage, Yann prend des photos. \u00c7a aussi, <strong>elle adore\u00a0: se faire photographier par son mari dans de telles situations. Les voyeurs semblent ne pas \u00eatre d\u00e9cid\u00e9s \u00e0 se satisfaire du simple plaisir des yeux.<\/strong> Tant mieux car Anna est dans un tel \u00e9tat qu\u2019elle n\u2019attend plus que \u00e7a\u00a0: \u00ab\u00a0<em>J\u2019\u00e9tais hors de moi en commen\u00e7ant \u00e0 les sucer tour \u00e0 tour. Puis, ils m\u2019ont prise, chacun \u00e0 leur tour.<span class=\"Apple-converted-space\" >\u00a0 <\/span>Pas de sodo car cet orifice est r\u00e9serv\u00e9 \u00e0 mon mari. Mais ils ne m\u2019ont pas m\u00e9nag\u00e9e, bien au contraire et pour mon plus grand plaisir. J\u2019aime le sexe brutal, violent, les p\u00e9n\u00e9trations sans douceur et j\u2019ai joui \u00e0 plusieurs reprises. Ils sont revenus dans ma bouche. J\u2019en ai fait jouir un, deux, puis trois et enfin le dernier est venu exploser entre mes l\u00e8vres, m\u2019inondant avec de longues d\u00e9charges. J\u2019avais la bouche pleine, j\u2019\u00e9tais heureuse d\u2019avoir re\u00e7u la jouissance abondante de mes partenaires entre mes l\u00e8vres. \u00bb<\/em><\/p> <p class=\"p1\">Les voyeurs se sont ensuite \u00e9loign\u00e9s\u00a0: \u00ab\u00a0<em>Cette fois, mon mari a laiss\u00e9 tomber l\u2019appareil photos pour me prendre \u00e0 son tour. Il \u00e9tait tr\u00e8s excit\u00e9 et moi apr\u00e8s une telle aventure, je l\u2019\u00e9tais encore plus.\u00a0\u00bb<\/em><\/p> <p><strong>A lire aussi &gt;&gt; <a href=\"https:\/\/www.union.fr\/recits\/histoire-de-sexe-le-gang-bang-de-lea-435491.html#post-435491\">Le gang-bang de L\u00e9a !<\/a><\/strong><\/p> <p><strong>A lire aussi &gt;&gt; <a href=\"https:\/\/www.union.fr\/recits\/histoire-porno-le-gang-bang-de-ma-femme-13821.html#post-13821\">Le gang-bang de ma femme<\/a><\/strong><\/p> ","protected":false},"excerpt":{"rendered":"<p>Anna, nous raconte l&rsquo;histoire de son premier gang-bang accompagn\u00e9e de son mari pour immortaliser ce moment unique.<\/p>\n","protected":false},"author":7,"featured_media":436852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,8],"tags":[322,564,619,1753],"class_list":["post-436815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaporama-accueil","category-menu_site","category-recits","tag-couple","tag-exhibitionnisme","tag-plage","tag-voyeurs"],"_links":{"self":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/436815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/comments?post=436815"}],"version-history":[{"count":1,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/436815\/revisions"}],"predecessor-version":[{"id":436853,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/posts\/436815\/revisions\/436853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media\/436852"}],"wp:attachment":[{"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/media?parent=436815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/categories?post=436815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.union.fr\/wp-json\/wp\/v2\/tags?post=436815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}